{"id":40345,"date":"2026-07-09T12:57:29","date_gmt":"2026-07-09T10:57:29","guid":{"rendered":"https:\/\/shop.mastinell.com\/producto\/pinta-la-vinya-amb-vi\/"},"modified":"2026-07-09T13:07:33","modified_gmt":"2026-07-09T11:07:33","slug":"pinta-la-vinya-amb-vi","status":"publish","type":"product","link":"https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/","title":{"rendered":"Pinta la vinya amb vi"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Apunta&#8217;t a aquesta activitat per al pr\u00f2xim 18 de juliol a les 19h en Mastinell.<\/p>\n<p>Qu\u00e8 inclou aquesta activitat?<\/p>\n<p>Passeig per les vinyes: Comen\u00e7arem amb un petit recorregut per les vinyes de l&#8217;hotel perqu\u00e8 els assistents connectin amb l&#8217;entorn.<\/p>\n<p>Taller de pintura amb vi: Una activitat molt especial impartida per Marta Ara\u00f1\u00f3, on el grup far\u00e0 un taller utilitzant el nostre propi vi com a pintura.<\/p>\n<p>Degustaci\u00f3 i aperitiu: Mentre pinten, gaudiran d&#8217;una copa de vi Mastinell i d&#8217;un petit aperitiu.<\/p>\n<p>Per a finalitzar la reserva d&#8217;aquesta experi\u00e8ncia, una vegada hagis realitzat la compra, consulta les dates disponibles amb el nostre equip d&#8217;Atenci\u00f3 al client, a trav\u00e9s del nostre WhatsApp (+34 662 60 06 32) o via email en <a href=\"mailto:info@hotelmastinell.com\">info@hotelmastinell.com<\/a><\/p>\n","protected":false},"featured_media":40342,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[135],"product_tag":[],"class_list":["post-40345","product","type-product","status-publish","has-post-thumbnail","product_cat-regala-enoturismo-ca","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pinta la vinya amb vi - Mastinell<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pinta la vinya amb vi - Mastinell\" \/>\n<meta property=\"og:description\" content=\"Apunta&#039;t a aquesta activitat per al pr\u00f2xim 18 de juliol a les 19h en Mastinell.  Qu\u00e8 inclou aquesta activitat?  Passeig per les vinyes: Comen\u00e7arem amb un petit recorregut per les vinyes de l&#039;hotel perqu\u00e8 els assistents connectin amb l&#039;entorn.  Taller de pintura amb vi: Una activitat molt especial impartida per Marta Ara\u00f1\u00f3, on el grup far\u00e0 un taller utilitzant el nostre propi vi com a pintura.  Degustaci\u00f3 i aperitiu: Mentre pinten, gaudiran d&#039;una copa de vi Mastinell i d&#039;un petit aperitiu.  Per a finalitzar la reserva d&#039;aquesta experi\u00e8ncia, una vegada hagis realitzat la compra, consulta les dates disponibles amb el nostre equip d&#039;Atenci\u00f3 al client, a trav\u00e9s del nostre WhatsApp (+34 662 60 06 32) o via email en info@hotelmastinell.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/\" \/>\n<meta property=\"og:site_name\" content=\"Mastinell\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CavaHotelMastinell\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T11:07:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.mastinell.com\/wp-content\/uploads\/2026\/07\/Vineyard_At_Sunset._original_2929685.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.mastinell.com\\\/ca\\\/producto\\\/pinta-la-vinya-amb-vi\\\/\",\"url\":\"https:\\\/\\\/shop.mastinell.com\\\/ca\\\/producto\\\/pinta-la-vinya-amb-vi\\\/\",\"name\":\"Pinta la vinya amb vi - Mastinell\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastinell.agencialiverpool.test\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.mastinell.com\\\/ca\\\/producto\\\/pinta-la-vinya-amb-vi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.mastinell.com\\\/ca\\\/producto\\\/pinta-la-vinya-amb-vi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.mastinell.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Vineyard_At_Sunset._original_2929685.jpg\",\"datePublished\":\"2026-07-09T10:57:29+00:00\",\"dateModified\":\"2026-07-09T11:07:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.mastinell.com\\\/ca\\\/producto\\\/pinta-la-vinya-amb-vi\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.mastinell.com\\\/ca\\\/producto\\\/pinta-la-vinya-amb-vi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/shop.mastinell.com\\\/ca\\\/producto\\\/pinta-la-vinya-amb-vi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.mastinell.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Vineyard_At_Sunset._original_2929685.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.mastinell.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Vineyard_At_Sunset._original_2929685.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.mastinell.com\\\/ca\\\/producto\\\/pinta-la-vinya-amb-vi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shop.mastinell.com\\\/ca\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pinta la vinya amb vi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mastinell.agencialiverpool.test\\\/#website\",\"url\":\"https:\\\/\\\/mastinell.agencialiverpool.test\\\/\",\"name\":\"Mastinell\",\"description\":\"Tienda Oficial\",\"publisher\":{\"@id\":\"https:\\\/\\\/mastinell.agencialiverpool.test\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mastinell.agencialiverpool.test\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mastinell.agencialiverpool.test\\\/#organization\",\"name\":\"Mastinell\",\"url\":\"https:\\\/\\\/mastinell.agencialiverpool.test\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/mastinell.agencialiverpool.test\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.mastinell.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Mastinell-Cava-y-Hotel-scaled-1.webp\",\"contentUrl\":\"https:\\\/\\\/shop.mastinell.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Mastinell-Cava-y-Hotel-scaled-1.webp\",\"width\":2560,\"height\":531,\"caption\":\"Mastinell\"},\"image\":{\"@id\":\"https:\\\/\\\/mastinell.agencialiverpool.test\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CavaHotelMastinell\",\"https:\\\/\\\/www.instagram.com\\\/cavahotel_mastinell\\\/?hl=es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pinta la vinya amb vi - Mastinell","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/","og_locale":"ca_ES","og_type":"article","og_title":"Pinta la vinya amb vi - Mastinell","og_description":"Apunta't a aquesta activitat per al pr\u00f2xim 18 de juliol a les 19h en Mastinell.  Qu\u00e8 inclou aquesta activitat?  Passeig per les vinyes: Comen\u00e7arem amb un petit recorregut per les vinyes de l'hotel perqu\u00e8 els assistents connectin amb l'entorn.  Taller de pintura amb vi: Una activitat molt especial impartida per Marta Ara\u00f1\u00f3, on el grup far\u00e0 un taller utilitzant el nostre propi vi com a pintura.  Degustaci\u00f3 i aperitiu: Mentre pinten, gaudiran d'una copa de vi Mastinell i d'un petit aperitiu.  Per a finalitzar la reserva d'aquesta experi\u00e8ncia, una vegada hagis realitzat la compra, consulta les dates disponibles amb el nostre equip d'Atenci\u00f3 al client, a trav\u00e9s del nostre WhatsApp (+34 662 60 06 32) o via email en info@hotelmastinell.com","og_url":"https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/","og_site_name":"Mastinell","article_publisher":"https:\/\/www.facebook.com\/CavaHotelMastinell","article_modified_time":"2026-07-09T11:07:33+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/shop.mastinell.com\/wp-content\/uploads\/2026\/07\/Vineyard_At_Sunset._original_2929685.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/","url":"https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/","name":"Pinta la vinya amb vi - Mastinell","isPartOf":{"@id":"https:\/\/mastinell.agencialiverpool.test\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/#primaryimage"},"image":{"@id":"https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.mastinell.com\/wp-content\/uploads\/2026\/07\/Vineyard_At_Sunset._original_2929685.jpg","datePublished":"2026-07-09T10:57:29+00:00","dateModified":"2026-07-09T11:07:33+00:00","breadcrumb":{"@id":"https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/#primaryimage","url":"https:\/\/shop.mastinell.com\/wp-content\/uploads\/2026\/07\/Vineyard_At_Sunset._original_2929685.jpg","contentUrl":"https:\/\/shop.mastinell.com\/wp-content\/uploads\/2026\/07\/Vineyard_At_Sunset._original_2929685.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/shop.mastinell.com\/ca\/producto\/pinta-la-vinya-amb-vi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shop.mastinell.com\/ca\/tienda\/"},{"@type":"ListItem","position":2,"name":"Pinta la vinya amb vi"}]},{"@type":"WebSite","@id":"https:\/\/mastinell.agencialiverpool.test\/#website","url":"https:\/\/mastinell.agencialiverpool.test\/","name":"Mastinell","description":"Tienda Oficial","publisher":{"@id":"https:\/\/mastinell.agencialiverpool.test\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mastinell.agencialiverpool.test\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/mastinell.agencialiverpool.test\/#organization","name":"Mastinell","url":"https:\/\/mastinell.agencialiverpool.test\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/mastinell.agencialiverpool.test\/#\/schema\/logo\/image\/","url":"https:\/\/shop.mastinell.com\/wp-content\/uploads\/2025\/01\/Mastinell-Cava-y-Hotel-scaled-1.webp","contentUrl":"https:\/\/shop.mastinell.com\/wp-content\/uploads\/2025\/01\/Mastinell-Cava-y-Hotel-scaled-1.webp","width":2560,"height":531,"caption":"Mastinell"},"image":{"@id":"https:\/\/mastinell.agencialiverpool.test\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CavaHotelMastinell","https:\/\/www.instagram.com\/cavahotel_mastinell\/?hl=es"]}]}},"_links":{"self":[{"href":"https:\/\/shop.mastinell.com\/ca\/wp-json\/wp\/v2\/product\/40345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.mastinell.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.mastinell.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/shop.mastinell.com\/ca\/wp-json\/wp\/v2\/product\/40345\/revisions"}],"predecessor-version":[{"id":40350,"href":"https:\/\/shop.mastinell.com\/ca\/wp-json\/wp\/v2\/product\/40345\/revisions\/40350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.mastinell.com\/ca\/wp-json\/wp\/v2\/media\/40342"}],"wp:attachment":[{"href":"https:\/\/shop.mastinell.com\/ca\/wp-json\/wp\/v2\/media?parent=40345"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.mastinell.com\/ca\/wp-json\/wp\/v2\/product_brand?post=40345"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.mastinell.com\/ca\/wp-json\/wp\/v2\/product_cat?post=40345"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.mastinell.com\/ca\/wp-json\/wp\/v2\/product_tag?post=40345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}